{"id":1001,"date":"2015-05-11T13:21:14","date_gmt":"2015-05-11T11:21:14","guid":{"rendered":"http:\/\/schalasch.de\/wp1\/wp-content\/uploads\/2015\/05\/1.PlatzMalwettbewerbMai2015_3.jpg"},"modified":"2018-07-10T21:06:00","modified_gmt":"2018-07-10T19:06:00","slug":"1-platzmalwettbewerbmai2015_3","status":"inherit","type":"attachment","link":"https:\/\/schalasch.de\/ru\/1-platz-beim-malwettbewerb\/1-platzmalwettbewerbmai2015_3\/","title":{"rendered":"1.PlatzMalwettbewerbMai2015_3"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"class_list":["post-1001","attachment","type-attachment","status-inherit","hentry","media_category-angebote","media_category-dozenten","media_category-werke"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/schalasch.de\/wp1\/wp-content\/uploads\/2015\/05\/1.PlatzMalwettbewerbMai2015_3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"183\" height=\"250\" src=\"https:\/\/schalasch.de\/wp1\/wp-content\/uploads\/2015\/05\/1.PlatzMalwettbewerbMai2015_3-219x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/schalasch.de\/wp1\/wp-content\/uploads\/2015\/05\/1.PlatzMalwettbewerbMai2015_3-219x300.jpg 219w, https:\/\/schalasch.de\/wp1\/wp-content\/uploads\/2015\/05\/1.PlatzMalwettbewerbMai2015_3-748x1024.jpg 748w, https:\/\/schalasch.de\/wp1\/wp-content\/uploads\/2015\/05\/1.PlatzMalwettbewerbMai2015_3.jpg 1256w\" sizes=\"auto, (max-width: 183px) 100vw, 183px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Interview <\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1256,"height":1720,"file":"2015\/05\/1.PlatzMalwettbewerbMai2015_3.jpg","sizes":{"thumbnail":{"file":"1.PlatzMalwettbewerbMai2015_3-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/schalasch.de\/wp1\/wp-content\/uploads\/2015\/05\/1.PlatzMalwettbewerbMai2015_3-150x150.jpg"},"medium":{"file":"1.PlatzMalwettbewerbMai2015_3-219x300.jpg","width":219,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/schalasch.de\/wp1\/wp-content\/uploads\/2015\/05\/1.PlatzMalwettbewerbMai2015_3-219x300.jpg"},"large":{"file":"1.PlatzMalwettbewerbMai2015_3-748x1024.jpg","width":748,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/schalasch.de\/wp1\/wp-content\/uploads\/2015\/05\/1.PlatzMalwettbewerbMai2015_3-748x1024.jpg"},"full":{"file":"1.PlatzMalwettbewerbMai2015_3.jpg","width":1256,"height":1720,"mime_type":"image\/jpeg","source_url":"https:\/\/schalasch.de\/wp1\/wp-content\/uploads\/2015\/05\/1.PlatzMalwettbewerbMai2015_3.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":932,"source_url":"https:\/\/schalasch.de\/wp1\/wp-content\/uploads\/2015\/05\/1.PlatzMalwettbewerbMai2015_3.jpg","_links":{"self":[{"href":"https:\/\/schalasch.de\/ru\/wp-json\/wp\/v2\/media\/1001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schalasch.de\/ru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/schalasch.de\/ru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/schalasch.de\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schalasch.de\/ru\/wp-json\/wp\/v2\/comments?post=1001"}]}}